{"id":49020,"date":"2025-05-15T17:57:48","date_gmt":"2025-05-15T15:57:48","guid":{"rendered":"https:\/\/www.sailcom.ch\/product\/product\/"},"modified":"2025-06-04T21:28:05","modified_gmt":"2025-06-04T19:28:05","slug":"event_49020","status":"publish","type":"product","link":"https:\/\/www.sailcom.ch\/fr\/produit\/event_49020\/","title":{"rendered":"Plausch Segeln auf der Sunbeam Aurora ab Thalwil"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Lust auf einen entspannten, aber trotzdem aktiven Segelabend auf dem Z\u00fcrichsee? Komm mit an Bord der Sunbeam 22.1 Aurora und geniesse das Abendsegeln ab Thalwil \u2013 gef\u00fchrt von unserer erfahrenen Skipperin Anna.<\/p>\n<p>Kosten: ca. 20\u201340 CHF (je nach Teilnehmerzahl)<\/p>\n<p>WANN ? Treffpunkt ist um 17:55 Uhr direkt beim Boot (Hafen Farbsteig Thalwil \/ Platz 131). Abfahrt dann p\u00fcnktlich um 18:00 Uhr<\/p>\n<p>WER ? Sowohl Sailcom-Mitglieder als auch externe G\u00e4ste sind herzlich willkommen!<br \/>\n\u2022 Sailcom Mitglieder melden sich direkt via Sailcom Webseite an.<br \/>\n\u2022 EXTERNE G\u00c4STE melden sich direkt beim Bootsteam via WhatsApp oder via E-mail<\/p>\n<p>WIE ?<br \/>\n\u2022 WhatsApp Link: https:\/\/chat.whatsapp.com\/LsiIJTfC9ij8KfszVUUIXU<br \/>\n\u2022 E-mail Kontaktdetails im PDF auf Seite 5\/12 https:\/\/www.sailcom.ch\/wp-content\/uploads\/2024\/08\/240825-Standortinfo-Thalwil.pdf<\/p>\n<p>WAS erwartet dich?<br \/>\n\u2022 Ein stimmungsvoller Segelabend bei jedem verantwortbaren Wetter<br \/>\n\u2022 Mitsegeln, entspannen oder aktiv mitanpacken \u2013 ganz wie Du willst<br \/>\n\u2022 Gemeinschaft, Wind, Wasser und gute Laune<\/p>\n<p>! WICHTIG !<br \/>\n\u2022 Bitte saubere (rutschfeste) Schuhe mitbringen<br \/>\n\u2022 Zahlung vor Ort in bar oder per Twint<br \/>\n\u2022 Bei Absage bitte mindestens 48 Stunden vorher per WhatsApp Bescheid geben. Kurzfristige Absagen oder Nichterscheinen werden vollst\u00e4ndig verrechnet. Fair is Fair.<\/p>\n<p>Leinen los \u2013 wir freuen uns auf dich!<\/p>\n","protected":false},"author":3510,"featured_media":27969,"template":"","meta":{"_acf_changed":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":""},"product_brand":[],"product_cat":[15],"product_tag":[],"sailcom-capability":[],"sailcom-location":[348],"sailcom-event-type":[364],"sailcom-boat-type":[],"class_list":{"0":"post-49020","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorised","7":"sailcom-location-zurichsee","8":"sailcom-event-type-sail-along","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"product-type-sc_event"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/product\/49020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/users\/3510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/media\/27969"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/media?parent=49020"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/product_brand?post=49020"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/product_cat?post=49020"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/product_tag?post=49020"},{"taxonomy":"sailcom-capability","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/sailcom-capability?post=49020"},{"taxonomy":"sailcom-location","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/sailcom-location?post=49020"},{"taxonomy":"sailcom-event-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/sailcom-event-type?post=49020"},{"taxonomy":"sailcom-boat-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/fr\/wp-json\/wp\/v2\/sailcom-boat-type?post=49020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}