{"id":54193,"date":"2025-09-20T18:15:09","date_gmt":"2025-09-20T16:15:09","guid":{"rendered":"https:\/\/www.sailcom.ch\/product\/product\/"},"modified":"2025-10-19T11:35:38","modified_gmt":"2025-10-19T09:35:38","slug":"event_54193","status":"publish","type":"product","link":"https:\/\/www.sailcom.ch\/en\/product\/event_54193\/","title":{"rendered":"Gennacker-Segeln ab Thalwil mit Skipper Niclas auf der Sunbeam Aurora"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Lust Gennacker-segeln zu lernen oder \u00fcben? Komm mit an Bord der Sunbeam 22.1 Aurora und geniesse das einfache Gennackerseglen ab Thalwil \u2013 gef\u00fchrt von unserem erfahrenen Skipper Niclas.<br \/>\n(Bei zu starken oder unstabilen Wind\/Wetter, werden wir ohne Gennacker segeln)<\/p>\n<p>Kosten: CHF 30\u201345 CHF (je nach Teilnehmerzahl)<\/p>\n<p>WANN ? Treffpunkt ist um 15:55 Uhr direkt beim Boot (Hafen Farbsteig Thalwil \/ Platz 131). Abfahrt dann p\u00fcnktlich um 16:00 Uhr<\/p>\n<p>WER ?  Sowohl Sailcom-Mitglieder als auch externe G\u00e4ste sind herzlich willkommen!<br \/>\n\u2022 Sailcom Mitglieder melden sich direkt via Sailcom Webseite an.<br \/>\n\u2022 EXTERNE G\u00c4STE melden sich direkt beim Bootsteam via WhatsApp oder via E-mail <\/p>\n<p>WIE ?<br \/>\n\u2022 WhatsApp Link: https:\/\/chat.whatsapp.com\/LsiIJTfC9ij8KfszVUUIXU<br \/>\n\u2022 E-mail Kontaktdetails im PDF auf Seite 5\/12  https:\/\/www.sailcom.ch\/wp-content\/uploads\/2024\/08\/240825-Standortinfo-Thalwil.pdf<\/p>\n<p>WAS erwartet dich?<br \/>\n\u2022 Ein sch\u00f6nen Segelt\u00f6rn bei jedem verantwortbaren Wetter<br \/>\n\u2022 Mitsegeln, Gennacker-segeln \u00fcben<br \/>\n\u2022 Gemeinschaft, Wind, Wasser und gute Laune<\/p>\n<p>! WICHTIG !<br \/>\n\u2022 Bitte saubere (rutschfeste) Schuhe mitbringen<br \/>\n\u2022 Zahlung vor Ort in bar oder per Twint<br \/>\n\u2022 Wird nur bei mindestens 2 anmeldungen durchgef\u00fchrt.<br \/>\n\u2022 Bei Absage bitte mindestens 48 Stunden vorher per WhatsApp Bescheid geben. Kurzfristige Absagen oder Nichterscheinen werden vollst\u00e4ndig verrechnet. Fair is Fair<\/p>\n<p>Leinen los \u2013 wir freuen uns auf Dich!\u2003<\/p>\n","protected":false},"author":1396,"featured_media":0,"template":"","meta":{"_acf_changed":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":""},"product_brand":[],"product_cat":[15],"product_tag":[],"sailcom-capability":[],"sailcom-location":[348],"sailcom-event-type":[378],"sailcom-boat-type":[],"class_list":{"0":"post-54193","1":"product","2":"type-product","3":"status-publish","5":"product_cat-uncategorised","6":"sailcom-location-zurichsee","7":"sailcom-event-type-genisegeln","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"product-type-sc_event"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product\/54193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/users\/1396"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media?parent=54193"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_brand?post=54193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_cat?post=54193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_tag?post=54193"},{"taxonomy":"sailcom-capability","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-capability?post=54193"},{"taxonomy":"sailcom-location","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-location?post=54193"},{"taxonomy":"sailcom-event-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-event-type?post=54193"},{"taxonomy":"sailcom-boat-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-boat-type?post=54193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}