{"id":45733,"date":"2025-02-27T14:36:53","date_gmt":"2025-02-27T13:36:53","guid":{"rendered":"https:\/\/www.sailcom.ch\/product\/product\/"},"modified":"2025-03-19T08:47:31","modified_gmt":"2025-03-19T07:47:31","slug":"event_45733","status":"publish","type":"product","link":"https:\/\/www.sailcom.ch\/en\/product\/event_45733\/","title":{"rendered":"Weiterbildung Bootsunterhalt &amp; Auswintern"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Weiterbildung Bootsunterhalt &amp; Auswintern <\/p>\n<p>Ort: Barkenhafen Nidau, Schlossstrasse 24, 2560 Nidau<br \/>\nDauer: 1 Kurstag<br \/>\nVeranstalter: SailCom in Zusammenarbeit mit Bieler Segelcenter GmbH<\/p>\n<p>Kursbeschreibung:<br \/>\nDieser praxisorientierte Event richtet sich an alle Bootsteammitglieder und interessierte Helfer:innen, die sich grundlegendes Wissen zum Bootsunterhalt und Auswintern aneignen m\u00f6chten. <\/p>\n<p>In Kombination aus wenig Theorie und viel Praxis lernen die Teilnehmer:innen die wichtigsten Arbeitsschritte und Sicherheitsvorkehrungen unter Anleitung durch einen gelernten Bootsbauer,  Coach und Lehrer kennen und wenden diese dann direkt an.<\/p>\n<p>Inhalte:<br \/>\n\u2022\tKennen und beachten der Sicherheitsmassnahmen, Kranarbeiten<br \/>\n\u2022\tReinigung von Schale und Deck, Schleifpolitur &amp; Maschine, Versiegelung<br \/>\n\u2022\tUnterwasserbereich aufarbeiten &amp; Farbe auftragen<br \/>\n\u2022\tKontrolle des stehenden und laufenden Guts<br \/>\n\u2022\tMast stellen &amp; ausrichten, Wantenspannung einstellen, Segel anschlagen<br \/>\n\u2022\tFunktionskontrollen<\/p>\n<p>Ablauf:<br \/>\n08:30 Uhr Kafi &amp; Gipfeli<br \/>\n09:00 Uhr Theorie Einf\u00fchrung<br \/>\n09:45 Uhr Pause<br \/>\n10:00 Uhr Praxisblock<br \/>\n12:00 Uhr Mittagspause<br \/>\n13:00 Uhr Praxis<br \/>\n17:30 Uhr Abschluss<\/p>\n<p>Es wird wetterfeste Kleidung empfohlen, die auch schmutzig werden darf und Farbspritzer aush\u00e4lt.<\/p>\n<p>\ud83d\udce9 Kontakt: Andreas Schraner, segeln@segelcenter.ch<br \/>\n\ud83d\udcde 076 589 51 31<\/p>\n","protected":false},"author":3388,"featured_media":37004,"template":"","meta":{"_acf_changed":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":""},"product_brand":[],"product_cat":[15],"product_tag":[],"sailcom-capability":[],"sailcom-location":[338],"sailcom-event-type":[531,380],"sailcom-boat-type":[],"class_list":{"0":"post-45733","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorised","7":"sailcom-location-bielersee","8":"sailcom-event-type-kurse-bootsteams","9":"sailcom-event-type-maintenance","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"product-type-sc_event"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product\/45733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/users\/3388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media\/37004"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media?parent=45733"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_brand?post=45733"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_cat?post=45733"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_tag?post=45733"},{"taxonomy":"sailcom-capability","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-capability?post=45733"},{"taxonomy":"sailcom-location","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-location?post=45733"},{"taxonomy":"sailcom-event-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-event-type?post=45733"},{"taxonomy":"sailcom-boat-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-boat-type?post=45733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}