{"id":30228,"date":"2024-04-30T11:41:36","date_gmt":"2024-04-30T09:41:36","guid":{"rendered":"https:\/\/www.sailcom.ch\/product\/product\/"},"modified":"2024-04-30T11:41:36","modified_gmt":"2024-04-30T09:41:36","slug":"event_30228","status":"publish","type":"product","link":"https:\/\/www.sailcom.ch\/en\/product\/event_30228\/","title":{"rendered":"Feierabend-Segeln"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Den Arbeitstag auf dem Bodensee ausklingen lassen und dabei einige Seemeilen zur\u00fccklegen? Wir segeln ungezwungen den Wind- und Wetterverh\u00e4ltnissen angepasst und geniessen im Anschluss nat\u00fcrlich den Ankertrunk im Hafen. Leinen los!<\/p>\n<p>Kosten: 80 Fr. werden durch die Anzahl Teilnehmer aufgeteilt.<br \/>\n\u00dcber die Durchf\u00fchrung wird am Vorabend entschieden. <\/p>\n<p>Das Bootsteam der TANSANIT<\/p>\n","protected":false},"author":2737,"featured_media":1718,"template":"","meta":{"_acf_changed":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":""},"product_brand":[],"product_cat":[15],"product_tag":[],"sailcom-capability":[],"sailcom-location":[339],"sailcom-event-type":[364],"sailcom-boat-type":[],"class_list":{"0":"post-30228","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorised","7":"sailcom-location-bodensee","8":"sailcom-event-type-sail-along","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-sc_event"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product\/30228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/users\/2737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media\/1718"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media?parent=30228"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_brand?post=30228"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_cat?post=30228"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_tag?post=30228"},{"taxonomy":"sailcom-capability","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-capability?post=30228"},{"taxonomy":"sailcom-location","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-location?post=30228"},{"taxonomy":"sailcom-event-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-event-type?post=30228"},{"taxonomy":"sailcom-boat-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-boat-type?post=30228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}