{"id":17579,"date":"2023-10-25T21:12:59","date_gmt":"2023-10-25T19:12:59","guid":{"rendered":"https:\/\/www.sailcom.ch\/product\/product\/"},"modified":"2023-12-30T22:52:49","modified_gmt":"2023-12-30T21:52:49","slug":"event_17579","status":"publish","type":"product","link":"https:\/\/www.sailcom.ch\/en\/product\/event_17579\/","title":{"rendered":"Arbeitstag an der First 27 SE &quot;Aiolos&quot;"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Die &quot;Aiolos&quot; wird in den Winterschlaf geschickt: Bei guter Witterung Unterwasserschiff anschleifen und streichen, Schale polieren, Innenraum reinigen und konservieren. Zuletzt Schiff zudecken.<br \/>\nMitnehmen: Arbeitskleidung zum Malen und Polieren, saubere Schuhe, eigenes, bew\u00e4hrtes Putzmaterial usw., Selbstverpflegung oder gemeinsame Mittagspause auf eigene Rechnung in nahegelegenem Restaurant.<br \/>\nTreffpunkt um 10.00 Uhr beim Winterlager \u00f6stlich neben der SBS-Werft (Autofahrt Richtung F\u00e4hre). Dauer ca. 5 Stunden (werden als Helferstunden f\u00fcr B-Status gutgeschrieben).<\/p>\n","protected":false},"author":2804,"featured_media":1530,"template":"","meta":{"_acf_changed":false,"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":""},"product_brand":[],"product_cat":[214],"product_tag":[],"sailcom-capability":[],"sailcom-location":[339],"sailcom-event-type":[380],"sailcom-boat-type":[],"class_list":{"0":"post-17579","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-maintenance","7":"sailcom-location-bodensee","8":"sailcom-event-type-maintenance","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"product-type-sc_event"},"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product\/17579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/users\/2804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media\/1530"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/media?parent=17579"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_brand?post=17579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_cat?post=17579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/product_tag?post=17579"},{"taxonomy":"sailcom-capability","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-capability?post=17579"},{"taxonomy":"sailcom-location","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-location?post=17579"},{"taxonomy":"sailcom-event-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-event-type?post=17579"},{"taxonomy":"sailcom-boat-type","embeddable":true,"href":"https:\/\/www.sailcom.ch\/en\/wp-json\/wp\/v2\/sailcom-boat-type?post=17579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}