{"id":60036,"date":"2026-01-31T21:02:05","date_gmt":"2026-01-31T20:02:05","guid":{"rendered":"https:\/\/www.sailcom.ch\/?post_type=scm_magazin&#038;p=60036"},"modified":"2026-03-13T15:12:01","modified_gmt":"2026-03-13T14:12:01","slug":"leinen-los","status":"publish","type":"scm_magazin","link":"https:\/\/www.sailcom.ch\/de\/magazin\/leinen-los\/","title":{"rendered":"Die Leinen und Schoten &#8211; und der richtige Umgang damit."},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"60036\" class=\"elementor elementor-60036\" data-elementor-post-type=\"scm_magazin\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f672763 e-flex e-con-boxed e-con e-parent\" data-id=\"f672763\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43be965 elementor-widget elementor-widget-text-editor\" data-id=\"43be965\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Es gibt viele Wege, mit den Leinen und Tauen auf einem Schiff umzugehen, je nach Zweck jedoch nur wenige wirklich gute.<\/strong><\/p><p>Von Marcel Trachsel und Roland Grieder.<\/p><p><strong>Aufr\u00e4umen und vorbereiten<\/strong><\/p><p>Kommt man auf ein Schiff, kann es sein, dass zun\u00e4chst eine knappe Viertelstunde Arbeit ansteht. Jemand hat alle Taue zum Babeli aufgewickelt. F\u00fcr grosse Festmacherseile auf Reserve, die Trossen, ergibt das Sinn. Bei Schoten, Fallen und Trimmleinen verz\u00f6gert es jedoch das Startklarmachen deutlich.<\/p><p>Hat das Bootsteam eine klare Ordnung, gilt diese. Sind Seiltaschen vorhanden, geh\u00f6ren die Leinen ungewickelt hinein. Jede Leine wird geb\u00fcschelt abgelegt, eine neben der anderen. Auch Winschen eignen sich gut, um die Buchten einer Schot dar\u00fcber zu legen. Das funktioniert ohne Babeli.<\/p><p><strong>Auf See<\/strong><\/p><p>Wenn wir ein Seil sauber in Buchten legen, drehen wir das Seil jeweils so, dass die neue Buchte die gleiche Richtung erh\u00e4lt wie die vorherigen. Dadurch speichern wir Drehkr\u00e4fte im Tauwerk. Diese Kr\u00e4fte l\u00f6sen sich, sobald das Seil unter Last l\u00e4uft.<\/p><p>Tests mit einem Gennacker zeigten ein deutliches Resultat. Wird die Leeschot freigegeben und das Fall schnell gefahren, liegt die Wahrscheinlichkeit bei rund 50 Prozent, dass sich Seile mit gespeicherter Drehung so verdrehen, dass sie blockieren. W\u00e4hrend einer Regatta ist das inakzeptabel. Man verliert sofort mehrere Bootsl\u00e4ngen. Zudem bleibt w\u00e4hrend einer Regatta keine Zeit, Leinen aufzuschlaufen oder sich abseits der optimalen Position aufzuhalten. Seiltaschen geh\u00f6ren deshalb zur Standardausr\u00fcstung auf Regattaschiffen.<\/p><p>Auch Fahrtensegler m\u00f6chten Risiken bei starkem Wind minimieren. Leinen kommen deshalb so in die Taschen, wie sie sich auf dem Cockpitboden abgelegt haben. Hat ein Schiff keine Seiltaschen, k\u00f6nnen die Enden der Leinen w\u00e4hrend des Segelns in die Kaj\u00fcte h\u00e4ngen. Auf breiten Cockpits kann man jeder Leine einen festen Platz zuweisen. Grundsatz auf See bleibt gleich. Aufr\u00e4umen, aufr\u00e4umen und nochmals aufr\u00e4umen. Die skippernde Person muss hier konsequent bleiben, um der Verantwortung an Bord gerecht zu werden.<\/p><p><strong>Beim Belegen<\/strong><\/p><p>Auch beim Belegen einer Klampe gibt es ein besonders sinnvolles Vorgehen. Das Seil wird vom weiter entfernten Klampenhorn einmal um den Klampenfuss gelegt. Der Grund liegt in der Physik. Die starke Umlenkung erzeugt Reibung. Bereits eine einzige Runde \u00fcbernimmt den gr\u00f6ssten Teil der Last, weil die Reibung mit jeder zus\u00e4tzlichen Umschlingung exponentiell zunimmt.<\/p><p>Danach folgen je ein Achterschlag \u00fcber die beiden H\u00f6rner und ein weiterer Rundt\u00f6rn. Damit ist die Leine sicher belegt. Im Hafen ersetzt ein Beschlagsknoten, auch Kopfschlag genannt, den letzten Rundt\u00f6rn.<\/p><p><strong>Seitw\u00e4rts parkieren<\/strong><\/p><p>Gute Seemannschaft, oft auch hohe Schule genannt, zeigt sich darin, kleinere Herausforderungen elegant zu l\u00f6sen. Ein typisches Beispiel ist das l\u00e4ngsseitige Anlegen am Steg, besonders wenn die L\u00fccke kurz ist oder Schwell in den Hafen steht.<\/p><p>Wer in dieser Situation Bug- und Achterleine sehr kurz nimmt, also exakt auf die Parkl\u00fccke abstimmt, blockiert die Bewegung des Schiffes im Schwell. Sinkt das Wasser, wirken die Leinen wie eine Schaukel. Die Wasserverdr\u00e4ngung des Schiffes presst den Rumpf gegen den Steg. Die Klampenwurzel erreicht schnell ihre physikalische Belastungsgrenze.<\/p><p>Ein Segelboot liegt im Schwell l\u00e4ngsseits nur dann ruhig, wenn zwei lange Springs stark gespannt werden. Idealerweise sind sie gleich lang und kreuzen sich etwa auf H\u00f6he der breitesten Stelle des Rumpfes. Die Elastizit\u00e4t der Leinen erlaubt wenige Zentimeter L\u00e4ngsbewegung und entlastet dadurch die Klampen.<\/p><p>Bug- und Achterleine bleiben dagegen relativ lose. Sie verhindern nur, dass das Schiff seitlich ausbricht. Dadurch reduzieren sich seitliche St\u00f6sse deutlich. Im Idealfall reicht dann ein einzelner Fender. Das ist ein guter Pr\u00fcfstein f\u00fcr saubere Seemannschaft. Je weniger Fender ben\u00f6tigt werden, desto besser ist das Schiff vert\u00e4ut.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Leinenarbeit geh\u00f6rt zum seglerischen Handwerk. Festmacher, Schoten, Fallen und Springs erf\u00fcllen an Bord unterschiedliche Aufgaben. Der Artikel erkl\u00e4rt wichtige Begriffe der Leinenarbeit und zeigt, wie du Leinen sicher belegst, f\u00fchrst und im Hafen oder unter Segel korrekt einsetzt.<\/p>\n","protected":false},"author":3736,"featured_media":61352,"comment_status":"closed","ping_status":"closed","template":"","scm_category":[495],"scm_tag":[482],"class_list":["post-60036","scm_magazin","type-scm_magazin","status-publish","has-post-thumbnail","hentry","scm_category-segelpraxis","scm_tag-seemannschaft"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_magazin\/60036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_magazin"}],"about":[{"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/types\/scm_magazin"}],"author":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/users\/3736"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/comments?post=60036"}],"version-history":[{"count":11,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_magazin\/60036\/revisions"}],"predecessor-version":[{"id":61362,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_magazin\/60036\/revisions\/61362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/media\/61352"}],"wp:attachment":[{"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/media?parent=60036"}],"wp:term":[{"taxonomy":"scm_category","embeddable":true,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_category?post=60036"},{"taxonomy":"scm_tag","embeddable":true,"href":"https:\/\/www.sailcom.ch\/de\/wp-json\/wp\/v2\/scm_tag?post=60036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}